{"id":1943,"date":"2024-10-12T17:17:26","date_gmt":"2024-10-12T16:17:26","guid":{"rendered":"https:\/\/therapeutjeroen.be\/?p=1943"},"modified":"2024-10-13T14:01:16","modified_gmt":"2024-10-13T13:01:16","slug":"leren-mediteren-zitten-zonder-zweven","status":"publish","type":"post","link":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/","title":{"rendered":"Leren Mediteren. Zitten Zonder Zweven."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van deze praktijk. Zodat ze ervoor kunnen kiezen (of niet) om meer kalmte  in hun leven te brengen en hun welzijn te versterken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In opdracht van Vrijetijdsdienst Mortsel. Wil je weten hoe je in de toekomst kunt deelnemen, of hoe we deze workshops naar jouw organisatie kunnen brengen? Stuur me gerust een berichtje!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/aankondiging-Mortsel-Leren-Mediteren.png\" alt=\"\" class=\"wp-image-1944\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van deze praktijk. Zodat ze ervoor kunnen kiezen (of niet) om meer kalmte in hun leven te brengen en hun welzijn te versterken. In opdracht van Vrijetijdsdienst Mortsel. Wil je weten hoe je in de toekomst kunt deelnemen, of hoe we deze workshops naar jouw organisatie kunnen brengen? Stuur me gerust een berichtje!<\/p>","protected":false},"author":2,"featured_media":1945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[47,52],"tags":[49,50,48,51],"class_list":["post-1943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nieuws","category-workshops","tag-meditatie","tag-mediteren","tag-nieuws","tag-workshops","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jeroen Walravens\"\/>\n\t<meta name=\"google-site-verification\" content=\"M4g6IV6pH4iNlbZVThy_-H8oSF_QmKpbwCysAESL29Q\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"nl_NL\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Therapeut Jeroen - Integratief en lichaamsgericht psychotherapeut\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen\" \/>\n\t\t<meta property=\"og:description\" content=\"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1724\" \/>\n\t\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-12T16:17:26+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-13T13:01:16+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/jeroenspagina\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#blogposting\",\"name\":\"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen\",\"headline\":\"Leren Mediteren. Zitten Zonder Zweven.\",\"author\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/author\\\/jeroen\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/wp-content\\\/uploads\\\/buddha-beeldje-scaled.webp\",\"width\":1724,\"height\":2560},\"datePublished\":\"2024-10-12T17:17:26+01:00\",\"dateModified\":\"2024-10-13T14:01:16+01:00\",\"inLanguage\":\"nl-NL\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#webpage\"},\"articleSection\":\"Nieuws, Workshops, Meditatie, Mediteren, Nieuws, Workshops\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/nieuws\\\/#listItem\",\"name\":\"Nieuws\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/nieuws\\\/#listItem\",\"position\":2,\"name\":\"Nieuws\",\"item\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/nieuws\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#listItem\",\"name\":\"Leren Mediteren. Zitten Zonder Zweven.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#listItem\",\"position\":3,\"name\":\"Leren Mediteren. Zitten Zonder Zweven.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/nieuws\\\/#listItem\",\"name\":\"Nieuws\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#organization\",\"name\":\"Jeroen Walravens - Psychotherapeut\",\"description\":\"Integratief en lichaamsgericht psychotherapeut Integratief Psychotherapaut Jeroen Walravens\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/\",\"telephone\":\"+32494189923\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/wp-content\\\/uploads\\\/cropped-cropped-logo-met-lijntje.png\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#organizationLogo\",\"width\":992,\"height\":273},\"image\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jeroenspagina\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/author\\\/jeroen\\\/#author\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/author\\\/jeroen\\\/\",\"name\":\"Jeroen Walravens\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38ec7233aa1580ed6658a3b9c4c3b86c555fa60676937be1b219ca478ca901c3?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Jeroen Walravens\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#webpage\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/\",\"name\":\"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen\",\"description\":\"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/author\\\/jeroen\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/author\\\/jeroen\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/wp-content\\\/uploads\\\/buddha-beeldje-scaled.webp\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#mainImage\",\"width\":1724,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/leren-mediteren-zitten-zonder-zweven\\\/#mainImage\"},\"datePublished\":\"2024-10-12T17:17:26+01:00\",\"dateModified\":\"2024-10-13T14:01:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/\",\"name\":\"Jeroen Walravens\",\"description\":\"Integratief en lichaamsgericht psychotherapeut\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen","description":"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van","canonical_url":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"M4g6IV6pH4iNlbZVThy_-H8oSF_QmKpbwCysAESL29Q","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#blogposting","name":"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen","headline":"Leren Mediteren. Zitten Zonder Zweven.","author":{"@id":"https:\/\/therapeutjeroen.be\/nl\/author\/jeroen\/#author"},"publisher":{"@id":"https:\/\/therapeutjeroen.be\/nl\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp","width":1724,"height":2560},"datePublished":"2024-10-12T17:17:26+01:00","dateModified":"2024-10-13T14:01:16+01:00","inLanguage":"nl-NL","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#webpage"},"isPartOf":{"@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#webpage"},"articleSection":"Nieuws, Workshops, Meditatie, Mediteren, Nieuws, Workshops"},{"@type":"BreadcrumbList","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl#listItem","position":1,"name":"Home","item":"https:\/\/therapeutjeroen.be\/nl","nextItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/#listItem","name":"Nieuws"}},{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/#listItem","position":2,"name":"Nieuws","item":"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/","nextItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#listItem","name":"Leren Mediteren. Zitten Zonder Zweven."},"previousItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#listItem","position":3,"name":"Leren Mediteren. Zitten Zonder Zweven.","previousItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/#listItem","name":"Nieuws"}}]},{"@type":"Organization","@id":"https:\/\/therapeutjeroen.be\/nl\/#organization","name":"Jeroen Walravens - Psychotherapeut","description":"Integratief en lichaamsgericht psychotherapeut Integratief Psychotherapaut Jeroen Walravens","url":"https:\/\/therapeutjeroen.be\/nl\/","telephone":"+32494189923","logo":{"@type":"ImageObject","url":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/cropped-cropped-logo-met-lijntje.png","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#organizationLogo","width":992,"height":273},"image":{"@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/jeroenspagina\/"]},{"@type":"Person","@id":"https:\/\/therapeutjeroen.be\/nl\/author\/jeroen\/#author","url":"https:\/\/therapeutjeroen.be\/nl\/author\/jeroen\/","name":"Jeroen Walravens","image":{"@type":"ImageObject","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/38ec7233aa1580ed6658a3b9c4c3b86c555fa60676937be1b219ca478ca901c3?s=96&d=mm&r=g","width":96,"height":96,"caption":"Jeroen Walravens"}},{"@type":"WebPage","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#webpage","url":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/","name":"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen","description":"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/therapeutjeroen.be\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#breadcrumblist"},"author":{"@id":"https:\/\/therapeutjeroen.be\/nl\/author\/jeroen\/#author"},"creator":{"@id":"https:\/\/therapeutjeroen.be\/nl\/author\/jeroen\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp","@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#mainImage","width":1724,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/#mainImage"},"datePublished":"2024-10-12T17:17:26+01:00","dateModified":"2024-10-13T14:01:16+01:00"},{"@type":"WebSite","@id":"https:\/\/therapeutjeroen.be\/nl\/#website","url":"https:\/\/therapeutjeroen.be\/nl\/","name":"Jeroen Walravens","description":"Integratief en lichaamsgericht psychotherapeut","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/therapeutjeroen.be\/nl\/#organization"}}]},"og:locale":"nl_NL","og:site_name":"Therapeut Jeroen - Integratief en lichaamsgericht psychotherapeut","og:type":"article","og:title":"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen","og:description":"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van","og:url":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/","og:image":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp","og:image:secure_url":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp","og:image:width":1724,"og:image:height":2560,"article:published_time":"2024-10-12T16:17:26+00:00","article:modified_time":"2024-10-13T13:01:16+00:00","article:publisher":"https:\/\/www.facebook.com\/jeroenspagina\/","twitter:card":"summary_large_image","twitter:title":"Leren Mediteren. Zitten Zonder Zweven. - Therapeut Jeroen","twitter:description":"Heb jij er ooit al aan gedacht om te mediteren? Werd je dan afgeschrikt door complexe uitleg of zweverigheid? Dat is helemaal niet nodig! In oktober ontdekken 12 Mortselaars gedurende vier weken hoe eenvoudig het allemaal is. Tijdens 4 wekelijks sessies zien we alles wat je moet weten over de wat, waarom en hoe van","twitter:image":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/buddha-beeldje-scaled.webp"},"aioseo_meta_data":{"post_id":"1943","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-12 16:17:34","updated":"2025-06-03 22:52:11","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/therapeutjeroen.be\/nl\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/\" title=\"Nieuws\">Nieuws<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLeren Mediteren. Zitten Zonder Zweven.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/therapeutjeroen.be\/nl"},{"label":"Nieuws","link":"https:\/\/therapeutjeroen.be\/nl\/category\/nieuws\/"},{"label":"Leren Mediteren. Zitten Zonder Zweven.","link":"https:\/\/therapeutjeroen.be\/nl\/leren-mediteren-zitten-zonder-zweven\/"}],"_links":{"self":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts\/1943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/comments?post=1943"}],"version-history":[{"count":1,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts\/1943\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts\/1943\/revisions\/1946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/media\/1945"}],"wp:attachment":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/media?parent=1943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories?post=1943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/tags?post=1943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}