{"id":38,"count":1,"description":"","link":"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/","name":"Hersenletsel - NAH","slug":"hersenletsel-nah","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"M4g6IV6pH4iNlbZVThy_-H8oSF_QmKpbwCysAESL29Q\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/hersenletsel-nah\\\/#listItem\",\"name\":\"Hersenletsel - NAH\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/category\\\/hersenletsel-nah\\\/#listItem\",\"position\":2,\"name\":\"Hersenletsel - NAH\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#collectionpage\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/\",\"name\":\"Hersenletsel - NAH - Therapeut Jeroen\",\"inLanguage\":\"nl-NL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#organization\",\"name\":\"Jeroen Walravens - Psychotherapeut\",\"description\":\"Integratief en lichaamsgericht psychotherapeut Integratief Psychotherapaut Jeroen Walravens\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/\",\"telephone\":\"+32494189923\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/wp-content\\\/uploads\\\/cropped-cropped-logo-met-lijntje.png\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#organizationLogo\",\"width\":992,\"height\":273},\"image\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/38\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/jeroenspagina\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/\",\"name\":\"Jeroen Walravens\",\"description\":\"Integratief en lichaamsgericht psychotherapeut\",\"inLanguage\":\"nl-NL\",\"publisher\":{\"@id\":\"https:\\\/\\\/therapeutjeroen.be\\\/nl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hersenletsel - NAH - Therapeut Jeroen","description":"","canonical_url":"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"M4g6IV6pH4iNlbZVThy_-H8oSF_QmKpbwCysAESL29Q","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl#listItem","position":1,"name":"Home","item":"https:\/\/therapeutjeroen.be\/nl","nextItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/#listItem","name":"Hersenletsel - NAH"}},{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/#listItem","position":2,"name":"Hersenletsel - NAH","previousItem":{"@type":"ListItem","@id":"https:\/\/therapeutjeroen.be\/nl#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/#collectionpage","url":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/","name":"Hersenletsel - NAH - Therapeut Jeroen","inLanguage":"nl-NL","isPartOf":{"@id":"https:\/\/therapeutjeroen.be\/nl\/#website"},"breadcrumb":{"@id":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/therapeutjeroen.be\/nl\/#organization","name":"Jeroen Walravens - Psychotherapeut","description":"Integratief en lichaamsgericht psychotherapeut Integratief Psychotherapaut Jeroen Walravens","url":"https:\/\/therapeutjeroen.be\/nl\/","telephone":"+32494189923","logo":{"@type":"ImageObject","url":"https:\/\/therapeutjeroen.be\/wp-content\/uploads\/cropped-cropped-logo-met-lijntje.png","@id":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/#organizationLogo","width":992,"height":273},"image":{"@id":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/jeroenspagina\/"]},{"@type":"WebSite","@id":"https:\/\/therapeutjeroen.be\/nl\/#website","url":"https:\/\/therapeutjeroen.be\/nl\/","name":"Jeroen Walravens","description":"Integratief en lichaamsgericht psychotherapeut","inLanguage":"nl-NL","publisher":{"@id":"https:\/\/therapeutjeroen.be\/nl\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/therapeutjeroen.be\/nl\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHersenletsel - NAH\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/therapeutjeroen.be\/nl"},{"label":"Hersenletsel - NAH","link":"https:\/\/therapeutjeroen.be\/nl\/category\/hersenletsel-nah\/"}],"_links":{"self":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts?categories=38"},{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/groups?categories=38"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}