{"id":36,"count":5,"description":"","link":"https:\/\/therapeutjeroen.be\/nl\/category\/zelfzorg\/","name":"Zelfzorg","slug":"zelfzorg","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/posts?categories=36"},{"href":"https:\/\/therapeutjeroen.be\/nl\/wp-json\/wp\/v2\/groups?categories=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}